{"id":3849,"date":"2019-07-13T19:07:31","date_gmt":"2019-07-13T23:07:31","guid":{"rendered":"https:\/\/briwebapp.net\/chyrfm\/?p=3849"},"modified":"2019-07-12T10:19:22","modified_gmt":"2019-07-12T14:19:22","slug":"hit-list-july-13","status":"publish","type":"post","link":"https:\/\/briwebapp.net\/chyrfm\/uncategorized\/2019\/07\/hit-list-july-13\/","title":{"rendered":"Hit List &#8211; July 13"},"content":{"rendered":"<p>Shawn Mendes THREEpeats as champion!<\/p>\n\n<table id=\"tablepress-38\" class=\"tablepress tablepress-id-38\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">TW<\/th><th class=\"column-2\">LW<\/th><th class=\"column-3\">Artist<\/th><th class=\"column-4\">Title<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1(3)<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">Shawn Mendes<\/td><td class=\"column-4\">If I Can't Have You<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">Ed Sheeran &amp; Justin Bieber<\/td><td class=\"column-4\">I Don't Care<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">Katy Perry<\/td><td class=\"column-4\">Never Really Over<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">Jonas Brothers<\/td><td class=\"column-4\">Sucker<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">Taylor Swift<\/td><td class=\"column-4\">ME!<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">8<\/td><td class=\"column-3\">Dan &amp; Shay<\/td><td class=\"column-4\">Speechless<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">6<\/td><td class=\"column-3\">P!nk<\/td><td class=\"column-4\">Walk Me Home<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">10<\/td><td class=\"column-3\">Taylor Swift<\/td><td class=\"column-4\">You Need To Calm Down<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">7<\/td><td class=\"column-3\">Ellie Goulding<\/td><td class=\"column-4\">Close To Me<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">9<\/td><td class=\"column-3\">Halsey + Benny Blanco<\/td><td class=\"column-4\">Eastside<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">12<\/td><td class=\"column-3\">Sam Smith feat. Normany<\/td><td class=\"column-4\">Dancing With A Stranger<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">16<\/td><td class=\"column-3\">Shawn Mendes + Camilla Cabello<\/td><td class=\"column-4\">Senorita<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">11<\/td><td class=\"column-3\">Halsey<\/td><td class=\"column-4\">Without Me<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">15<\/td><td class=\"column-3\">Alessia Cara<\/td><td class=\"column-4\">Out of Love<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">13<\/td><td class=\"column-3\">Panic! At The Disco<\/td><td class=\"column-4\">High Hopes<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">14<\/td><td class=\"column-3\">Lennon Stella<\/td><td class=\"column-4\">La Di Da<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">18<\/td><td class=\"column-3\">5 Seconds Of Summer<\/td><td class=\"column-4\">Easier<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">17<\/td><td class=\"column-3\">Lewis, Dean<\/td><td class=\"column-4\">Be Alright<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">19<\/td><td class=\"column-3\">Felix Cartal + Lights<\/td><td class=\"column-4\">Love Me<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">-<\/td><td class=\"column-3\">Lewis Capaldi<\/td><td class=\"column-4\">Someone You Loved<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-38 from cache -->\n<div class=\"video-shortcode embed-container\"><iframe loading=\"lazy\" title=\"YouTube video player\" width=\"610\" height=\"355\" src=\"https:\/\/www.youtube.com\/embed\/oTJ-oqwxdZY\" frameborder=\"0\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Shawn Mendes THREEpeats as champion!","protected":false},"author":53,"featured_media":3863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"featured_img_display":"Yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"publishpress_future_action":{"enabled":false,"date":"2026-07-21 22:17:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"react_link":"https:\/\/mix967.ca\/uncategorized\/2019\/07\/hit-list-july-13\/","_links":{"self":[{"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/posts\/3849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/comments?post=3849"}],"version-history":[{"count":1,"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/posts\/3849\/revisions"}],"predecessor-version":[{"id":3850,"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/posts\/3849\/revisions\/3850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/media\/3863"}],"wp:attachment":[{"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/media?parent=3849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/categories?post=3849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/briwebapp.net\/chyrfm\/wp-json\/wp\/v2\/tags?post=3849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}